{"id":5018,"date":"2018-06-27T14:33:59","date_gmt":"2018-06-27T17:33:59","guid":{"rendered":"http:\/\/ubanews.com\/site\/?p=5018"},"modified":"2018-06-27T14:33:59","modified_gmt":"2018-06-27T17:33:59","slug":"reuniao-ordinaria-na-camara-municipal-aprovam-11-projetos","status":"publish","type":"post","link":"https:\/\/ubanews.com\/site\/2018\/06\/27\/reuniao-ordinaria-na-camara-municipal-aprovam-11-projetos\/","title":{"rendered":"Reuni\u00e3o Ordin\u00e1ria na C\u00e2mara Municipal aprovam 11 projetos"},"content":{"rendered":"<p>Na reuni\u00e3o ordin\u00e1ria da C\u00e2mara Municipal de Ub\u00e1 na data de segunda-feira (25\/06),os vereadores aprovaram 11 projetos, por unanimidade, quatro delas s\u00e3o projetos que autorizam abertura de cr\u00e9dito adicional especial junto ao or\u00e7amento municipal de 2018, denomina\u00e7\u00e3o de logradouro.<\/p>\n<p>S\u00e3o eles:&nbsp;<\/p>\n<p><em>Projeto de Lei n\u00b0 032\/18 que \u201cAutoriza abertura de Cr\u00e9ditos Adicionais Especiais no valor de 16.000,00 (dezesseis mil reais), junto ao Or\u00e7amento Municipal de 2018, com recurso proveniente do Minist\u00e9rio da Sa\u00fade, destinados aos custeios do Programa de Financiamento das A\u00e7\u00f5es de Alimenta\u00e7\u00e3o e Nutri\u00e7\u00e3o, no \u00e2mbito da Secretaria Municipal de Sa\u00fade\/Fundo Municipal de Sa\u00fade e d\u00e1 outras provid\u00eancias\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0033\/18 que \u201cAutoriza abertura de Cr\u00e9dito Adicional Especial no valor de R$ 80.000,00 (oitenta mil reais), junto ao Or\u00e7amento Municipal de 2018, com recurso proveniente do Minist\u00e9rio de Sa\u00fade, destinado a aquisi\u00e7\u00e3o de Ambul\u00e2ncia Tipo A, no \u00e2mbito da Secretaria Municipal de Sa\u00fade\/Fundo Municipal e d\u00e1 outras provid\u00eancias\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 034\/18 que \u201cAutoriza abertura de Cr\u00e9dito Adicional Especial no Valor de R$ 75.000,00 (setenta e cinco mil reais), junto ao Or\u00e7amento Municipal de 2018, com recurso proveniente do Minist\u00e9rio da Sa\u00fade, destinado a aquisi\u00e7\u00e3o de Consult\u00f3rio Odontol\u00f3gico para a Aten\u00e7\u00e3o Prim\u00e1ria, no \u00e2mbito da Secretaria Municipal de Sa\u00fade\/Fundo Municipal de Sa\u00fade e d\u00e1 outras provid\u00eancias\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 039\/18 que \u201cAutoriza abertura de Cr\u00e9ditos Adicionais Especiais no valor de R$ 300.000,00 (trezentos mil reais) junto ao Or\u00e7amento Municipal de 2018, para desenvolvimentos de A\u00e7\u00f5es do Projeto Olho Vivo, de Vigil\u00e2ncia por C\u00e2meras, e d\u00e1 outras providencias\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 01\/18 que \u201cD\u00e1 nova reda\u00e7\u00e3o ao par\u00e1grafo 4\u00b0 do art. 93 da Lei Complementar Municipal n\u00b0 191, de 26 de dezembro de 2016 que disp\u00f5e sobre a pol\u00edtica de prote\u00e7\u00e3o, conserva\u00e7\u00e3o, preserva\u00e7\u00e3o, controle, licenciamento e fiscaliza\u00e7\u00e3o do meio ambiente e melhoria da qualidade de vida no Munic\u00edpio de Ub\u00e1\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 020\/18 que \u201cAutoriza o Munic\u00edpio de Ub\u00e1 a adquirir, por doa\u00e7\u00e3o, im\u00f3vel destinado \u00e0 constru\u00e7\u00e3o de po\u00e7o artesiano, no lugar denominado C\u00f3rrego Alegre, nesta cidade\u201d.<\/em><\/p>\n<p>O Vereador Darci Pires da Silva solicitou a vista ao Projeto de Lei n\u00ba 020\/18 na reuni\u00e3o anterior, ele solicitou que comparece no plen\u00e1rio algum representante ou at\u00e9 mesmo o propriet\u00e1rio do terreno para que melhores esclarecimentos pudessem convencer, ningu\u00e9m esteve presente e assim devolveu o projeto. Mas o Vereador Edeir Pacheco pediu vista para a pr\u00f3xima reuni\u00e3o.<\/p>\n<p><em>Projeto de Lei n\u00b0 024\/17 que \u201cDisp\u00f5e sobre a cria\u00e7\u00e3o do dia de comemora\u00e7\u00e3o do anivers\u00e1rio do in\u00edcio das atividades da C\u00e2mara Municipal de Ub\u00e1\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 035\/18 que \u201cAltera a reda\u00e7\u00e3o de dispositivo de Lei n\u00b0 3.574, de 23.03.2007, que institui no Munic\u00edpio de Ub\u00e1 o Dia Municipal do Evang\u00e9lico e d\u00e1 outras provid\u00eancias\u201d<\/em>. O vereador Jos\u00e9 Roberto Filgueiras pediu vista a este projeto<\/p>\n<p><em>Projeto de Lei n\u00b0 036\/18 que \u201cDisp\u00f5e sobre a denomina\u00e7\u00e3o de Rua Albina de Paiva Lana a logradouro p\u00fablico desta cidade\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 027\/18 que \u201cDisp\u00f5e sobre a denomina\u00e7\u00e3o de Rua Jos\u00e9 Alfenas de Andrade a logradouro P\u00fablico desta cidade\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 028\/18 que \u201cDisp\u00f5e sobre a denomina\u00e7\u00e3o de Rua Leon Rivail Gomes a logradouro p\u00fablico desta cidade\u201d.<\/em><\/p>\n<p><em>Projeto de Lei n\u00b0 031\/18 que \u201cDisp\u00f5e sobre a denomina\u00e7\u00e3o de Rua Jaime Candian a logradouro p\u00fablico desta cidade\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na reuni\u00e3o ordin\u00e1ria da C\u00e2mara Municipal de Ub\u00e1 na data<\/p>\n","protected":false},"author":2,"featured_media":5019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-5018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camara-municipal"],"_links":{"self":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/5018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/comments?post=5018"}],"version-history":[{"count":0,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/5018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media\/5019"}],"wp:attachment":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media?parent=5018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/categories?post=5018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/tags?post=5018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}