{"id":283,"date":"2018-02-27T14:21:17","date_gmt":"2018-02-27T17:21:17","guid":{"rendered":"http:\/\/ubanews.com\/site\/?p=283"},"modified":"2018-03-02T08:26:02","modified_gmt":"2018-03-02T11:26:02","slug":"homem-de-30-anos-arranca-bolsa-da-vitima-que-vai-parar-na-uti","status":"publish","type":"post","link":"https:\/\/ubanews.com\/site\/2018\/02\/27\/homem-de-30-anos-arranca-bolsa-da-vitima-que-vai-parar-na-uti\/","title":{"rendered":"Homem de 30 anos arranca bolsa da vitima que vai parar na UTI"},"content":{"rendered":"<p>Um senhor e uma senhora, ambos com 71 anos de idade, relataram a PM que, por volta das 13h20min, quando eles transitavam com seu ciclomotor, pela rodovia que liga Guidoval a Ub\u00e1, um indiv\u00edduo, em uma motocicleta preta, se aproximou, puxando violentamente a bolsa que a passageira do ciclomotor carregava, jogando a v\u00edtima ao solo. Ap\u00f3s o fato, o autor evadiu sentido a cidade de Ub\u00e1, levando a bolsa da v\u00edtima. Em rastreamento, ele foi identificado como Jean Felipe Gon\u00e7alves, 30 anos, morador das proximidades de onde ocorreu o fato. Continuando o rastreamento, o autor foi localizado em sua resid\u00eancia, onde os policiais tamb\u00e9m localizaram uma bucha de maconha e um cigarro da mesma subst\u00e2ncia, materiais que foram apreendidos. Ainda, durante o registro do fato, foi verificado no sistema, um mandado de pris\u00e3o em desfavor do autor, sendo este cumprido. Assim, Jean foi preso e encaminhado \u00e0 DPJ local. Ressalta-se que Jean foi reconhecido por uma das v\u00edtimas que caiu do ciclomotor, j\u00e1 que a outra foi parar na UTI do Hospital Santa Isabel, onde permanece internada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um senhor e uma senhora, ambos com 71 anos de<\/p>\n","protected":false},"author":2,"featured_media":287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/comments?post=283"}],"version-history":[{"count":0,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media\/287"}],"wp:attachment":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media?parent=283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/categories?post=283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/tags?post=283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}