{"id":21360,"date":"2022-08-11T10:00:53","date_gmt":"2022-08-11T13:00:53","guid":{"rendered":"http:\/\/ubanews.com\/site\/?p=21360"},"modified":"2022-09-06T11:18:36","modified_gmt":"2022-09-06T14:18:36","slug":"uba-financia-bolsas-de-mestrado-para-professores-da-rede-municipal","status":"publish","type":"post","link":"https:\/\/ubanews.com\/site\/2022\/08\/11\/uba-financia-bolsas-de-mestrado-para-professores-da-rede-municipal\/","title":{"rendered":"Ub\u00e1 financia bolsas de Mestrado para professores da Rede Municipal"},"content":{"rendered":"<p style=\"font-weight: 400;\"><em>10 oportunidades em formato de bolsas de estudo ser\u00e3o oferecidas<\/em><\/p>\n<p style=\"font-weight: 400;\">A Prefeitura de Ub\u00e1, por meio da Secretaria Municipal de Educa\u00e7\u00e3o (SME), firmou parceria com o n\u00facleo acad\u00eamico do Centro de Pol\u00edticas P\u00fablicas e Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o da Universidade Federal de Juiz de Fora (CAEd\/UFJF) para financiar bolsas de Mestrado Profissional em Gest\u00e3o e Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o P\u00fablica (n\u00edvel&nbsp;<em>stricto sensu)<\/em>&nbsp;para profissionais em exerc\u00edcio na Rede Municipal de Ensino.<\/p>\n<p style=\"font-weight: 400;\">Ao todo, a SME oferecer\u00e1 10 bolsas de estudo. Os investimentos s\u00e3o da ordem de R$ 400 mil para pagamento do curso de Mestrado e custeio das despesas de hospedagem, transporte e alimenta\u00e7\u00e3o dos mestrandos.<\/p>\n<p style=\"font-weight: 400;\">Cerca de 180 professores do munic\u00edpio demonstraram interesse em participar da sele\u00e7\u00e3o, atrav\u00e9s de inscri\u00e7\u00f5es que foram realizadas via Formul\u00e1rio Eletr\u00f4nico entre os dias 1\u00ba e 10\/07.<\/p>\n<p style=\"font-weight: 400;\">Os postulantes \u00e0s vagas dever\u00e3o ser aprovados no Processo Seletivo e preencher os requisitos previstos no Edital 2022 do Programa de P\u00f3s-Gradua\u00e7\u00e3o Profissional em Gest\u00e3o e Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o P\u00fablica da UFJF. De acordo com o edital, as provas objetiva e dissertativa ser\u00e3o no dia 21 de agosto de 2022.<\/p>\n<p style=\"font-weight: 400;\">O Secret\u00e1rio Municipal de Educa\u00e7\u00e3o, Samuel Gazolla Lima, destacou que a concess\u00e3o das bolsas de mestrado para os professores vai refletir na qualidade do ensino em Ub\u00e1. \u201cO investimento no financiamento dessas bolsas de Mestrado trar\u00e1 grande retorno para a Educa\u00e7\u00e3o Municipal, uma vez que os mestrandos ter\u00e3o como objeto de estudo uma situa\u00e7\u00e3o pr\u00e1tica vivenciada na Rede Municipal de Ensino, trazendo diagn\u00f3sticos e propostas de interven\u00e7\u00e3o para melhorias e avan\u00e7os, al\u00e9m de atender a necessidade de qualifica\u00e7\u00e3o de pessoal\u201d, afirmou.<\/p>\n<p style=\"font-weight: 400;\"><strong>O Curso<\/strong><\/p>\n<p style=\"font-weight: 400;\">O Mestrado Profissional em Gest\u00e3o e Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o P\u00fablica da UFJF<em>&nbsp;<\/em>\u00e9 aprovado pela Capes e foi concebido para profissionais com inscri\u00e7\u00e3o efetiva nos sistemas p\u00fablicos de educa\u00e7\u00e3o&nbsp;b\u00e1sico, com o objetivo promover as&nbsp;qualidades profissionais necess\u00e1rias ao exerc\u00edcio eficiente dos novos pap\u00e9is que se atribuem ao gestor da&nbsp;educa\u00e7\u00e3o p\u00fablica.<\/p>\n<p style=\"font-weight: 400;\">O curso tem dura\u00e7\u00e3o de dois anos, com atividades organizadas em m\u00f3dulos presenciais, previstos para os meses de janeiro e&nbsp;julho, al\u00e9m de m\u00f3dulos on-line, oferecidos de mar\u00e7o a junho e de agosto a dezembro.<\/p>\n<p style=\"font-weight: 400;\">Os aprovados no Processo Seletivo 2022 dever\u00e3o confirmar sua pr\u00e9-matr\u00edcula no dia 07 de outubro. O in\u00edcio das aulas ser\u00e1 presencial, entre os dias 10 e 14 de outubro.<\/p>\n<p style=\"font-weight: 400;\">Assessoria de Comunica\u00e7\u00e3o<br \/>\nPrefeitura de Ub\u00e1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>10 oportunidades em formato de bolsas de estudo ser\u00e3o oferecidas<\/p>\n","protected":false},"author":2,"featured_media":5046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-21360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prefeitura-municipal"],"_links":{"self":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/21360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/comments?post=21360"}],"version-history":[{"count":0,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/21360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media\/5046"}],"wp:attachment":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media?parent=21360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/categories?post=21360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/tags?post=21360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}