{"id":14789,"date":"2020-01-25T20:50:05","date_gmt":"2020-01-25T23:50:05","guid":{"rendered":"http:\/\/ubanews.com\/site\/?p=14789"},"modified":"2020-01-27T14:00:42","modified_gmt":"2020-01-27T17:00:42","slug":"interditados-ponte-da-av-cristiano-rocas-e-rua-joao-groppo-bairro-ines-groppo","status":"publish","type":"post","link":"https:\/\/ubanews.com\/site\/2020\/01\/25\/interditados-ponte-da-av-cristiano-rocas-e-rua-joao-groppo-bairro-ines-groppo\/","title":{"rendered":"INTERDITADOS: PONTE DA AV. CRISTIANO RO\u00c7AS E RUA JO\u00c3O GROPPO &#8211; BAIRRO IN\u00caS GROPPO"},"content":{"rendered":"<div style=\"width: 840px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-14789-1\" width=\"840\" height=\"472\" autoplay preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4?_=1\" \/><a href=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4\">https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4<\/a><\/video><\/div>\n<p><strong>Nota Oficial 04 &#8211; A\u00e7\u00f5es de resposta \u00e0s chuvas em 25\/01\/2020<\/strong><\/p>\n<p>O munic\u00edpio de Ub\u00e1 foi atingido por chuvas intensas e severas&nbsp;no dia&nbsp;24 de janeiro.&nbsp;Diversos pontos de alagamentos&nbsp;foram registrados&nbsp;pela cidade, al\u00e9m do extravasamento da calha do Ribeir\u00e3o Ub\u00e1 na Av. Comendador Jacinto S. S.Lima (Beira-Rio), causando a inunda\u00e7\u00e3o de toda a avenida e suas pontes.<\/p>\n<p>\u00c0s 11h de hoje o munic\u00edpio publicou um Decreto de Situa\u00e7\u00e3o de Emerg\u00eancia, em edi\u00e7\u00e3o extraordin\u00e1ria do Di\u00e1rio Oficial.<br \/>\nDoa\u00e7\u00f5es de alimentos n\u00e3o perec\u00edveis e \u00e1gua mineral podem ser entregues no F\u00f3rum Cultural. Preferencialmente, garrafas de at\u00e9 5 litros, vedadas. &nbsp;<\/p>\n<p>Integrantes do Sistema de Comando de Opera\u00e7\u00f5es reuniram-se novamente \u00e0s 18h deste s\u00e1bado (25). O n\u00famero de desalojados chegou a 30 pessoas, todas encaminhadas \u00e0 casa de familiares. Tr\u00eas pessoas foram desabrigadas e encaminhadas para a Casa Cidad\u00e3. Nove im\u00f3veis est\u00e3o interditados, nos bairros: In\u00eas Gr\u00f4ppo, Industrial, Centro, Meu Sonho e S\u00e3o Domingos.<\/p>\n<p>A capta\u00e7\u00e3o e distribui\u00e7\u00e3o de \u00e1gua foi restabelecida na ETA Miragaia \u00e0s 17h30, pela Copasa.<br \/>\nEm rela\u00e7\u00e3o aos acessos a distritos, foi restabelecida a passagem nas estradas de Ubari e Miragaia. A ponte do Santa Rosa foi recuperada provisoriamente, permitindo a passagem inclusive de ve\u00edculos pesados. A ponte do Aeroporto (Edinho Farinheiro) foi danificada. A passarela da rua Pedro Candian, no bairro Industrial, foi deslocada e sua reconstru\u00e7\u00e3o \u00e9 prioridade. A Ponte do C\u00f3rrego dos Mendes passar\u00e1 por recomposi\u00e7\u00e3o da prote\u00e7\u00e3o lateral.<\/p>\n<p>O Corpo de Bombeiros recebeu um total de 79 chamadas desde o dia 24. Somente a partir das 8h de hoje, foram recebidos 28 chamadas relacionadas \u00e0 chuva, em toda sua \u00e1rea de atua\u00e7\u00e3o (n\u00e3o apenas Ub\u00e1), principalmente relacionadas a risco de desmoronamento.<\/p>\n<p>Durante todo o s\u00e1bado, cerca de 150 funcion\u00e1rios da Prefeitura, al\u00e9m de volunt\u00e1rios, realizaram a\u00e7\u00f5es de limpeza, recupera\u00e7\u00e3o de estradas, interven\u00e7\u00f5es de tr\u00e2nsito e isolamento de \u00e1reas. Cerca de 44 caminh\u00f5es de lama foram retirados apenas na regi\u00e3o da Beira-Rio. As a\u00e7\u00f5es de limpeza permanecem neste domingo, e tamb\u00e9m nos pr\u00f3ximos dias. A Prefeitura esclarece que as a\u00e7\u00f5es est\u00e3o sendo feitas por prioridades, e que todas as regi\u00f5es da cidade receber\u00e3o as a\u00e7\u00f5es de recupera\u00e7\u00e3o e limpeza devidas nos pr\u00f3ximos dias. Cerca de 25 servidores da Secretaria de Desenvolvimento Social, com apoio de volunt\u00e1rios da Defensoria P\u00fablica em Ub\u00e1, percorreram diversos locais afetados em abordagens \u00e0s fam\u00edlias atingidas pelas chuvas.<\/p>\n<p>Interdi\u00e7\u00f5es<br \/>\n&#8211; A ponte Major Siqueira, na rua Cristiano Ro\u00e7as, segue interditada totalmente para passagem de ve\u00edculos e pedestres.<br \/>\n&#8211; A rua Jo\u00e3o Gr\u00f4ppo, no bairro In\u00eas Gr\u00f4ppo, segue interditada para passagem de ve\u00edculos. A \u00e1rea pr\u00f3xima ao n\u00famero 228 foi completamente isolada, devido ao risco de desmoronamento de um pr\u00e9dio. O local receber\u00e1 monitoramento di\u00e1rio. A Energisa j\u00e1 providencia o corte de fornecimento de energia el\u00e9trica no poste e dois im\u00f3veis em risco no local. Recomenda-se aos motoristas que evitem a regi\u00e3o.<\/p>\n<p>A alternativa de tr\u00e2nsito \u00e9:<br \/>\n&#8211; Para ve\u00edculos pesados: desvio \u00e0 direita ap\u00f3s a ponte do Posto Zema, em dire\u00e7\u00e3o ao frigor\u00edfico, passando pelos bairros Agroceres e Bom Pastor.<br \/>\n&#8211; Ve\u00edculos leves: desvio pela Rua Nossa Senhora Aparecida.<\/p>\n<p>Novo boletim com atualiza\u00e7\u00f5es do evento ser\u00e1 encaminhado \u00e0 imprensa, e publicado nos canais oficiais da Prefeitura por volta das 13h deste domingo (26\/01\/2020).<\/p>\n<p>Alerta a popula\u00e7\u00e3o: H\u00e1 previs\u00e3o de mais chuvas para as pr\u00f3ximas horas.<\/p>\n<p>Orienta\u00e7\u00f5es aos cidad\u00e3os<br \/>\nOrienta-se \u00e0s pessoas que N\u00c3O dirijam-se para os locais afetados pelas enchentes, especialmente \u00e0 Avenida Beira-Rio. A presen\u00e7a de curiosos prejudica os trabalhos de restabelecimento da cidade, al\u00e9m de caracterizar s\u00e9rio risco.<\/p>\n<p>\u2022 Se sua casa estiver em risco de alagamento ou desabamento, saia do local e acione imediatamente o Corpo de Bombeiros (Telefone 193);<br \/>\n\u2022 N\u00e3o se arrisque em atravessar a p\u00e9 ou com ve\u00edculos as ruas e \u00e1reas alagadas;<\/p>\n<p>Sa\u00fade<br \/>\nA Secretaria Municipal de Sa\u00fade adverte sobre os perigos do contato com a \u00e1gua das cheias que pode trazer riscos para a sa\u00fade da popula\u00e7\u00e3o. Entre as principais doen\u00e7as est\u00e3o a leptospirose, a hepatite, a febre tif\u00f3ide e a c\u00f3lera. Todas s\u00e3o transmitidas pelo contato direto ou indireto com a \u00e1gua contaminada.<br \/>\nAs caracter\u00edsticas mais comuns para identificar o cont\u00e1gio s\u00e3o n\u00e1useas, febre e diarreia, dor muscular principalmente na panturrilha, olhos avermelhados. Quando n\u00e3o tratadas, essas doen\u00e7as podem ser fatais. Por isso, para quem apresentar dois ou mais sintomas, \u00e9 importante procurar ajuda m\u00e9dica.<br \/>\n\u00c9 poss\u00edvel barrar a contamina\u00e7\u00e3o tomando algumas medidas. Deve-se evitar o contato direto com a \u00e1gua ou a lama das enchentes, n\u00e3o andar com os p\u00e9s descal\u00e7os e n\u00e3o consumir alimentos que tiveram o contato com essa \u00e1gua.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/channel\/UCm0EcguUF8_FXRnrYtA_1qg?view_as=subscriber\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8297 size-full\" src=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube.jpg\" alt=\"\" width=\"800\" height=\"100\" srcset=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube.jpg 800w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube-300x38.jpg 300w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube-768x96.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/chat.whatsapp.com\/Ki0Fq5pPy8i3SDsr2pJgpx\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a><\/span><\/strong> para ser membro no grupo de whatsapp e ser notificado sempre quando tiver uma nova not\u00edcia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota Oficial 04 &#8211; A\u00e7\u00f5es de resposta \u00e0s chuvas em<\/p>\n","protected":false},"author":2,"featured_media":14791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/14789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/comments?post=14789"}],"version-history":[{"count":0,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/14789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media\/14791"}],"wp:attachment":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media?parent=14789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/categories?post=14789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/tags?post=14789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}