{"id":14739,"date":"2020-01-24T10:12:15","date_gmt":"2020-01-24T13:12:15","guid":{"rendered":"http:\/\/ubanews.com\/site\/?p=14739"},"modified":"2020-01-24T10:12:15","modified_gmt":"2020-01-24T13:12:15","slug":"publicado-edital-de-concurso-publico-com-161-vagas","status":"publish","type":"post","link":"https:\/\/ubanews.com\/site\/2020\/01\/24\/publicado-edital-de-concurso-publico-com-161-vagas\/","title":{"rendered":"Publicado\u00a0Edital de Concurso P\u00fablico com 161 vagas"},"content":{"rendered":"<div style=\"width: 840px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-14739-1\" width=\"840\" height=\"472\" autoplay preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4?_=1\" \/><a href=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4\">https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4<\/a><\/video><\/div>\n<p style=\"font-weight: 400;\">A Prefeitura publicou nesta quinta-feira (23\/01) o&nbsp;Edital&nbsp;de Concurso P\u00fablico&nbsp;01\/2020 para preenchimento de 161 vagas com escolaridade de n\u00edvel fundamental, m\u00e9dio, m\u00e9dio\/t\u00e9cnico e superior&nbsp;. Os sal\u00e1rios variam de R$ 1278,72 a R$ 3.636,81.&nbsp;O Edital completo est\u00e1 dispon\u00edvel nos sites&nbsp;<a href=\"http:\/\/www.uba.mg.gov.br\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.uba.mg.gov.br&amp;source=gmail&amp;ust=1579957845726000&amp;usg=AFQjCNH-wGv6SkR0RqzhDYUXv4X3OWZpYQ\" target=\"_blank\" rel=\"noopener\"><u>www.uba.mg.gov.br<\/u><\/a>&nbsp;e&nbsp;<a href=\"http:\/\/www.gestaodeconcursos.com.br.\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.gestaodeconcursos.com.br.&amp;source=gmail&amp;ust=1579957845726000&amp;usg=AFQjCNGNk9b1Nq7D0GRr4I1kKy9mg5XZmQ\" target=\"_blank\" rel=\"noopener\"><u>www.gestaodeconcursos.com.br<\/u><u>.<\/u><\/a>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">Segundo o prefeito Edson Teixeira Filho, \u201cNosso concurso n\u00e3o visa aumentar a for\u00e7a de trabalho da Prefeitura. Trata-se de uma substitui\u00e7\u00e3o natural, em consequ\u00eancia da aposentadoria de nossos servidores, especialmente na \u00e1rea da Educa\u00e7\u00e3o. Os novos cargos criados dizem respeito \u00e0 Guarda Municipal, que trata-se de uma meta do nosso plano de governo e agora come\u00e7a a ser incorporado \u00e0 administra\u00e7\u00e3o municipal, e tamb\u00e9m de algumas forma\u00e7\u00f5es que s\u00e3o fruto da necessidade de especializa\u00e7\u00e3o dentro da gest\u00e3o municipal, como t\u00e9cnicos ambientais, engenheiro agrimensor, engenheiro eletricista, engenheiro de tr\u00e2nsito e engenheiro de sistemas\u201d, comentou.<\/p>\n<p style=\"font-weight: 400;\">Ser\u00e3o disponibilizadas vagas para os cargos de Agente Administrativo I, Professor AI (magist\u00e9rio), Assistente Administrativo I, Agente de Fiscaliza\u00e7\u00e3o, Fiscal Sanit\u00e1rio, T\u00e9cnico de Inform\u00e1tica, T\u00e9cnico Ambiental, T\u00e9cnico de Edifica\u00e7\u00e3o, T\u00e9cnico de Enfermagem 30h, T\u00e9cnico de Enfermagem 40h, Guarda Civil Municipal, Bibliotec\u00e1rio, Engenheiro de Tr\u00e2nsito, Bi\u00f3logo, Psic\u00f3logo, Assistente Social, Contador, Engenheiro Agrimensor, Engenheiro de Sistemas, Engenheiro Civil, Engenheiro Eletricista, Enfermeiro 30h, Enfermeiro 40h, Enfermeiro do Trabalho, M\u00e9dico Auditor, Dentista 30h, Dentista 40h, T\u00e9cnico em Educa\u00e7\u00e3o (supervis\u00e3o\/orienta\u00e7\u00e3o escolar) e Procurador Municipal.<\/p>\n<p style=\"font-weight: 400;\">O concurso ocorrer\u00e1 em quatro etapas: prova objetiva de m\u00faltipla escolha, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio para todos os cargos; teste de aptid\u00e3o f\u00edsica, de car\u00e1ter eliminat\u00f3rio, para o cargo Guarda Civil Municipal; prova de Avalia\u00e7\u00e3o Psicol\u00f3gica, de car\u00e1ter eliminat\u00f3rio, para o cargo de Guarda Civil Municipal; e prova de T\u00edtulos, de car\u00e1ter classificat\u00f3rio, para os cargos de n\u00edvel superior e para o cargo de n\u00edvel m\u00e9dio Professor AI (Magist\u00e9rio).<\/p>\n<p style=\"font-weight: 400;\">\u201cRealizar o concurso era um desejo, mas nos \u00faltimos dois anos n\u00e3o t\u00ednhamos seguran\u00e7a financeira que permitisse abrir novas despesas de sal\u00e1rios e encargos de previd\u00eancia, devido a reten\u00e7\u00e3o dos recursos feita pelo Governo do Estado. Somente agora, com a negocia\u00e7\u00e3o dessa d\u00edvida e o in\u00edcio do pagamento das parcelas, temos confian\u00e7a nessa iniciativa para dar esse importante passo\u201d, finalizou o prefeito Edson.<\/p>\n<p><strong>ASSESSORIA DE COMUNICA\u00c7\u00c3O PREFEITURA MUNICIPAL DE UB\u00c1<\/strong><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/channel\/UCm0EcguUF8_FXRnrYtA_1qg?view_as=subscriber\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8297 size-full\" src=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube.jpg\" alt=\"\" width=\"800\" height=\"100\" srcset=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube.jpg 800w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube-300x38.jpg 300w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube-768x96.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/chat.whatsapp.com\/Klxyu9HT5L47jDrThOvhLV\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a><\/span><\/strong> para ser membro no grupo de whatsapp e ser notificado sempre quando tiver uma nova not\u00edcia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura publicou nesta quinta-feira (23\/01) o&nbsp;Edital&nbsp;de Concurso P\u00fablico&nbsp;01\/2020 para<\/p>\n","protected":false},"author":2,"featured_media":3995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prefeitura-municipal"],"_links":{"self":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/14739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/comments?post=14739"}],"version-history":[{"count":0,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/14739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media\/3995"}],"wp:attachment":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media?parent=14739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/categories?post=14739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/tags?post=14739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}