{"id":14670,"date":"2020-01-11T14:52:30","date_gmt":"2020-01-11T17:52:30","guid":{"rendered":"http:\/\/ubanews.com\/site\/?p=14670"},"modified":"2020-05-04T11:02:03","modified_gmt":"2020-05-04T14:02:03","slug":"concluida-a-primeira-parte-da-reconstrucao-do-trevo-do-peixoto-filho","status":"publish","type":"post","link":"https:\/\/ubanews.com\/site\/2020\/01\/11\/concluida-a-primeira-parte-da-reconstrucao-do-trevo-do-peixoto-filho\/","title":{"rendered":"CONCLU\u00cdDA A PRIMEIRA PARTE DA RECONSTRU\u00c7\u00c3O DO TREVO DO PEIXOTO FILHO"},"content":{"rendered":"<div style=\"width: 840px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-14670-1\" width=\"840\" height=\"472\" autoplay preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4?_=1\" \/><a href=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4\">https:\/\/ubanews.com\/site\/wp-content\/uploads\/2020\/01\/Diviscrita.mp4<\/a><\/video><\/div>\n<p>O prefeito de Ub\u00e1 Edson Teixeira Filho se mostrou indignado: \u201cestava dando vergonha a situa\u00e7\u00e3o do trevo aqui do Peixoto Filho\u201d. Desabafou. Com certeza ele ouviu muitas reclama\u00e7\u00f5es acerca do problema. E realmente o problema era muito grave. Depois de uma negativa do DER, por\u00e9m com uma insist\u00eancia do Comandante tudo se resolveu. A prefeitura tomou \u00e0s r\u00e9deas, e, com recursos do munic\u00edpio, a primeira parte das obras est\u00e3o prontas. Segundo o Secret\u00e1rio de Obras Jo\u00e3o Gomes J\u00fanior, a recupera\u00e7\u00e3o total do trevo deve ficar pronta at\u00e9 o final do m\u00eas de mar\u00e7o. &nbsp;<strong>&nbsp;<\/strong><\/p>\n<p><em>As obras para reconstru\u00e7\u00e3o do Trevo do Peixoto Filho (Anel Vi\u00e1rio), uma demanda antiga da comunidade, seguem a todo vapor. Neste s\u00e1bado, o prefeito Edson e o secret\u00e1rio de Obras, Jo\u00e3o Gomes J\u00fanior, estiveram no local entre 9h30 e 10h30 acompanhando os trabalhos e \u00e0 disposi\u00e7\u00e3o para apresentar o projeto e atender \u00e0 imprensa.<\/em><\/p>\n<p><em>Trata-se de uma obra de grande volume.<\/em><\/p>\n<p>Assessoria de Imprensa da PMU.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/DrfVyIQKfo4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/channel\/UCm0EcguUF8_FXRnrYtA_1qg?view_as=subscriber\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8297 size-full\" src=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube.jpg\" alt=\"\" width=\"800\" height=\"100\" srcset=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube.jpg 800w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube-300x38.jpg 300w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2018\/10\/inscreva-se-no-You-Tube-768x96.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/chat.whatsapp.com\/Klxyu9HT5L47jDrThOvhLV\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a><\/span><\/strong> para ser membro no grupo de whatsapp e ser notificado sempre quando tiver uma nova not\u00edcia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Ub\u00e1 Edson Teixeira Filho se mostrou indignado:<\/p>\n","protected":false},"author":2,"featured_media":14671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prefeitura-municipal"],"_links":{"self":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/14670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/comments?post=14670"}],"version-history":[{"count":0,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/14670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media\/14671"}],"wp:attachment":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media?parent=14670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/categories?post=14670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/tags?post=14670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}