{"id":11992,"date":"2019-05-31T07:56:09","date_gmt":"2019-05-31T10:56:09","guid":{"rendered":"http:\/\/ubanews.com\/site\/?p=11992"},"modified":"2019-05-31T07:58:03","modified_gmt":"2019-05-31T10:58:03","slug":"centro-de-convivencia-peluso-sera-inaugurado-no-sabado","status":"publish","type":"post","link":"https:\/\/ubanews.com\/site\/2019\/05\/31\/centro-de-convivencia-peluso-sera-inaugurado-no-sabado\/","title":{"rendered":"Centro de Conviv\u00eancia Peluso ser\u00e1 inaugurado no s\u00e1bado"},"content":{"rendered":"<div>\n<p><a href=\"https:\/\/docs.google.com\/forms\/d\/14-gnGBZfSajC8zc6-h6rdnRkeN0rHTb4HDTW1g2GHe4\/viewform?vc=0&amp;c=0&amp;w=1&amp;edit_requested=true\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-11857 size-medium\" src=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2019\/05\/1-1-298x300.jpg\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/ubanews.com\/site\/wp-content\/uploads\/2019\/05\/1-1-298x300.jpg 298w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2019\/05\/1-1-150x150.jpg 150w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2019\/05\/1-1-768x773.jpg 768w, https:\/\/ubanews.com\/site\/wp-content\/uploads\/2019\/05\/1-1.jpg 994w\" sizes=\"auto, (max-width: 298px) 100vw, 298px\" \/><\/a>No pr\u00f3ximo s\u00e1bado, 1 de junho, a Prefeitura de Ub\u00e1, por meio da Secretaria de Desenvolvimento Social, inaugura o Centro de Conviv\u00eancia Peluso, que vai desenvolver suas atividades na Quadra Poliesportiva Julieta Moreira Mendes Peluso e na Academia da Sa\u00fade Jos\u00e9 Alfeu do Nascimento, no bairro Peluso.<\/p>\n<\/div>\n<div>\n<p>A solenidade de inaugura\u00e7\u00e3o ser\u00e1 a partir das 9 horas, e ter\u00e1 apresenta\u00e7\u00e3o de hip hop com os alunos da Escola Estadual Ces\u00e1rio Alvim, apresenta\u00e7\u00e3o de bal\u00e9, com usu\u00e1rios do CRAS S\u00e3o Jo\u00e3o e a capoeira da Associa\u00e7\u00e3o de Moradores. A Secretaria de Sa\u00fade tamb\u00e9m estar\u00e1 presente com os alunos de Medicina da Fagoc, realizando a aferi\u00e7\u00e3o de press\u00e3o arterial.<\/p>\n<p>O Centro vai oferecer oficinas culturais, l\u00fadicas, esportivas e de inclus\u00e3o social para os moradores daquele bairro e dos bairros vizinhos, todas gratuitas. Essas atividades v\u00e3o se somar \u00e0s que j\u00e1 s\u00e3o disponibilizadas pela Secretaria de Sa\u00fade, ampliando as possibilidades de uso do espa\u00e7o entre os moradores da regi\u00e3o. As oficinas s\u00e3o voltadas para crian\u00e7as, adolescentes, adultos e idosos, com objetivo de promover integra\u00e7\u00e3o, cidadania e o desenvolvimento das potencialidades desses usu\u00e1rios, gerando qualidade de vida.<\/p>\n<p>A implanta\u00e7\u00e3o de um projeto social naquela localidade foi uma prioridade eleita pelos moradores no Or\u00e7amento Participativo 2017\/2018. Todos est\u00e3o convidados a participar.<\/p>\n<p><strong>ASSESSORIA DE COMUNICA\u00c7\u00c3O PREFEITURA MUNICIPAL DE UB\u00c1<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No pr\u00f3ximo s\u00e1bado, 1 de junho, a Prefeitura de Ub\u00e1,<\/p>\n","protected":false},"author":2,"featured_media":9550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-11992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prefeitura-municipal"],"_links":{"self":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/11992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/comments?post=11992"}],"version-history":[{"count":0,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/posts\/11992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media\/9550"}],"wp:attachment":[{"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/media?parent=11992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/categories?post=11992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubanews.com\/site\/wp-json\/wp\/v2\/tags?post=11992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}